{"id":3466,"date":"2022-03-11T09:00:39","date_gmt":"2022-03-11T08:00:39","guid":{"rendered":"https:\/\/visuresmart.it\/news\/?p=3466"},"modified":"2022-03-01T11:21:28","modified_gmt":"2022-03-01T10:21:28","slug":"residenza-fittizia-cosa-si-rischia","status":"publish","type":"post","link":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/","title":{"rendered":"Residenza fittizia: cosa si rischia"},"content":{"rendered":"\n<p>Risulta essere piuttosto comune l&#8217;utilizzo improprio della <strong>residenza<\/strong>, utilizzandone una <strong>fittizia<\/strong> al fine di poter godere di sconti fiscali, quali lo sgravio delle imposte sulla seconda casa, e cos\u00ec via. Nonostante gli apparenti vantaggi, chi decide di spostare la propria residenza in un&#8217;altra abitazione, deve essere cosciente dei rischi che corre. Difatti, dichiarare di essere residenti in una casa, senza abitarci davvero, \u00e8 considerato un reato. <\/p>\n\n\n\n<p>Si definisce reato sia per l&#8217;irreperibilit\u00e0 del soggetto che, in caso di necessit\u00e0, non riceverebbe alcuna comunicazione, sia per falsa dichiarazione a un funzionario dell&#8217;Anagrafe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Residenza: di cosa si tratta<\/h2>\n\n\n\n<p>\u00c8 bene chiarire, per poter parlare di residenza fittizia, cosa sia effettivamente la <strong>residenza<\/strong> di un cittadino. Questa, nello specifico, \u00e8 <strong>l&#8217;abitazione dove il soggetto vive la sua quotidianit\u00e0, o, diversamente, vive per la maggior parte del tempo<\/strong>. Essendo, dunque, la residenza la dimora del cittadino \u00e8 vietato dichiarare la residenza in un&#8217;abitazione diversa dalla propria. <\/p>\n\n\n\n<p>La legge impone di dichiarare all&#8217;Anagrafe comunale la propria residenza entro 20 giorni dal trasferimento. Tale comunicazione avviene presso il Comune di destinazione che provvede poi a notificarlo al Comune da cui ci si \u00e8 spostati.<\/p>\n\n\n\n<p>L\u2019ufficio Anagrafe&nbsp;che riceve la notifica del cambio di residenza aggiorna i registri&nbsp;<strong>entro 48 ore<\/strong>.<\/p>\n\n\n\n<p>Dopo aver aggiornato i propri registri, l\u2019ufficio Anagrafe pu\u00f2 inviare la&nbsp;polizia municipale&nbsp;ad effettuare dei&nbsp;<strong>controlli&nbsp;<\/strong>presso l\u2019abitazione nuova del cittadino. Se da questi dovesse emergere che non \u00e8 residente dove ha dichiarato, allora il cambio di residenza sarebbe revocato.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cos\u2019\u00e8 la residenza fittizia?<\/h2>\n\n\n\n<p>Chiarito che la residenza deve coincidere con il luogo in cui il soggetto vive per la maggior parte dell&#8217;anno, si pu\u00f2 facilmente intuire, invece, cosa sia una residenza fittizia. Questa viene definita come il luogo in cui un soggetto una disponibilit\u00e0, ma non trascorre la sua vita. Solitamente si opta per la comunicazione di una residenza fittizia per alleggerire la propria posizione fiscale o godere di alcuni benefici. <\/p>\n\n\n\n<p>Tuttavia, come gi\u00e0 affermato, dichiarare all&#8217;anagrafe una residenza fittizia, comporta un illecito che costituisce reato.<\/p>\n\n\n\n<p>\u00c8 evidente che, costituendo reato, esistono delle sanzioni legate a questa pratica. Secondo quanto stabilisce la sentenza della Corte di Cassazione, n. 15651\/2014:  una residenza in un luogo diverso da quello della propria dimora abituale costituisce un reato di&nbsp;<strong>falso ideologico in atto pubblico<\/strong>.<\/p>\n\n\n\n<p>Per questa ragione, si rischia di incorrere in due tipi di sanzione:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>\u200bsanzione pratica<\/strong>: tutte le notifiche effettuate al nuovo indirizzo si considerano eseguite con il deposito presso la Casa Comunale. Si tratta della notifica per chi risulta essere irreperibile,<\/li><li><strong>sanzione penale<\/strong>: per il reato di falso in atto pubblico si prevede la&nbsp;<strong>reclusione fino a 2 anni<\/strong>&nbsp;e non inferiore a 3 mesi (art. 483 del codice penale).<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/visuresmart.it\/front\/Anagrafe_CertificatodiResidenza.aspx\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"129\" src=\"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2021\/05\/Banner-1-8-1024x129.png\" alt=\"\" class=\"wp-image-2458\" srcset=\"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2021\/05\/Banner-1-8-1024x129.png 1024w, https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2021\/05\/Banner-1-8-300x38.png 300w, https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2021\/05\/Banner-1-8-768x97.png 768w, https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2021\/05\/Banner-1-8-696x88.png 696w, https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2021\/05\/Banner-1-8-1068x135.png 1068w, https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2021\/05\/Banner-1-8.png 1614w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Come denunciare una residenza fittizia<\/h2>\n\n\n\n<p>Qualora voleste denunciare una residenza fittizia dovete rivolgervi all&#8217;<strong>ufficio Anagrafe del Comune<\/strong> dove si trova l&#8217;immobile. Ivi sar\u00e0 possibile segnalare il fatto, le persone coinvolte e l&#8217;indirizzo dell&#8217;abitazione. <\/p>\n\n\n\n<p>In seguito, l\u2019ufficio anagrafe avviser\u00e0 la polizia municipale in modo tale che provvedano ad effettuare dei&nbsp;<strong>controlli&nbsp;in loco&nbsp;<\/strong>per verificare la situazione di fatto segnalata. A quel punto, se la persona denunciata non viene trovata a casa&nbsp;per tre volte, il Comune disporr\u00e0 la&nbsp;\u201cmancata presenza al domicilio\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Come ottenere il certificato di residenza online<\/h2>\n\n\n\n<p>Tramite il servizio rapido e professionale di&nbsp;<a href=\"https:\/\/visuresmart.it\/\">VisureSmart.it<\/a>&nbsp;\u00e8 possibile richiedere&nbsp;<a href=\"https:\/\/visuresmart.it\/front\/Anagrafe_CertificatodiResidenza.aspx\">online<\/a> il Certificato di residenza. Il documento verr\u00e0 inviato tramite e-mail o, su richiesta, raccomandata a.r. I tempi necessari alla consegna sono solitamente di 15 giorni lavorativi. \u00c8&nbsp;inoltre possibile richiedere anche il&nbsp;<a href=\"https:\/\/visuresmart.it\/front\/Anagrafe_CertificatodiResidenza.aspx\">Certificato di residenza storico<\/a>. Si tratta di quel documento che consente di conoscere se un soggetto ha risieduto&nbsp;<strong>presso altri indirizzi<\/strong>&nbsp;dello stesso Comune o presso Comuni diversi. In quest\u2019ultimo caso il certificato riporta il nome del precedente Comune in cui era fissata la dimora abituale del soggetto e la&nbsp;<strong>data del trasferimento<\/strong>&nbsp;da un Comune all\u2019altro. Lo storico di Residenza pu\u00f2 riguardare i residenti o gli ex residenti di un comune, cos\u00ec come le persone decedute o emigrate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Risulta essere piuttosto comune l&#8217;utilizzo improprio della residenza, utilizzandone una fittizia al fine di poter godere di sconti fiscali, quali lo sgravio delle imposte sulla seconda casa, e cos\u00ec via. Nonostante gli apparenti vantaggi, chi decide di spostare la propria residenza in un&#8217;altra abitazione, deve essere cosciente dei rischi che corre. Difatti, dichiarare di essere [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[183,464,685],"class_list":["post-3466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casa-visure-smart","tag-certificato-di-residenza","tag-residenza","tag-residenza-fittizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Residenza fittizia: cosa si rischia<\/title>\r\n<meta name=\"description\" content=\"Cosa si rischia se si dichiara all&#039;anagrafe una residenza fittizia? Seppur porta apparenti vantaggi dichiarare il falso causa reato.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Residenza fittizia: cosa si rischia\" \/>\r\n<meta property=\"og:description\" content=\"Cosa si rischia se si dichiara all&#039;anagrafe una residenza fittizia? Seppur porta apparenti vantaggi dichiarare il falso causa reato.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/\" \/>\r\n<meta property=\"og:site_name\" content=\"VisureSmart News\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/visuresmart.it\/\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-03-11T08:00:39+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2022-03-01T10:21:28+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Visuresmart\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Visuresmart\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/\"},\"author\":{\"name\":\"Visuresmart\",\"@id\":\"https:\/\/visuresmart.it\/news\/#\/schema\/person\/f2480b0f8a8cfe03fbacc0a5a37f9b28\"},\"headline\":\"Residenza fittizia: cosa si rischia\",\"datePublished\":\"2022-03-11T08:00:39+00:00\",\"dateModified\":\"2022-03-01T10:21:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/\"},\"wordCount\":690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/visuresmart.it\/news\/#organization\"},\"image\":{\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg\",\"keywords\":[\"certificato di residenza\",\"residenza\",\"residenza fittizia\"],\"articleSection\":[\"Casa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/\",\"url\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/\",\"name\":\"Residenza fittizia: cosa si rischia\",\"isPartOf\":{\"@id\":\"https:\/\/visuresmart.it\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg\",\"datePublished\":\"2022-03-11T08:00:39+00:00\",\"dateModified\":\"2022-03-01T10:21:28+00:00\",\"description\":\"Cosa si rischia se si dichiara all'anagrafe una residenza fittizia? Seppur porta apparenti vantaggi dichiarare il falso causa reato.\",\"breadcrumb\":{\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#primaryimage\",\"url\":\"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg\",\"contentUrl\":\"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg\",\"width\":1920,\"height\":1080,\"caption\":\"Cosa si rischia con la residenza fittizia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/visuresmart.it\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Residenza fittizia: cosa si rischia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/visuresmart.it\/news\/#website\",\"url\":\"https:\/\/visuresmart.it\/news\/\",\"name\":\"VisureSmart News\",\"description\":\"Il blog che nasce con l&#039;intento di aiutarvi a trovare informazioni su casa, famiglia, auto, lavoro e imprese in modo rapido e semplificato!\",\"publisher\":{\"@id\":\"https:\/\/visuresmart.it\/news\/#organization\"},\"alternateName\":\"Visuresmart\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/visuresmart.it\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/visuresmart.it\/news\/#organization\",\"name\":\"News VisureSmart.it\",\"url\":\"https:\/\/visuresmart.it\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/visuresmart.it\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2020\/03\/Risorsa-2.png\",\"contentUrl\":\"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2020\/03\/Risorsa-2.png\",\"width\":513,\"height\":513,\"caption\":\"News VisureSmart.it\"},\"image\":{\"@id\":\"https:\/\/visuresmart.it\/news\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/visuresmart.it\/\",\"https:\/\/www.instagram.com\/visuresmart.it\/\"],\"description\":\"Visuresmart.it \u00e8 un portale unico specializzato nella richiesta di documenti burocratici, tanto per i professionisti quanto per i cittadini. I nostri servizi permettono di ottenere un contatto diretto con la Pubblica Amministrazione, l\u2019Anagrafe, la Camera di Commercio e il Tribunale. Il nostro team \u00e8 composto da professionisti del settore, esperti nell\u2019espletare pratiche e capaci di consigliare e indirizzare i nostri clienti verso le soluzioni migliori.\",\"email\":\"info@visuresmart.it\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/visuresmart.it\/news\/#\/schema\/person\/f2480b0f8a8cfe03fbacc0a5a37f9b28\",\"name\":\"Visuresmart\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/visuresmart.it\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/27e26115b2431936e33b4fc6115798f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/27e26115b2431936e33b4fc6115798f2?s=96&d=mm&r=g\",\"caption\":\"Visuresmart\"}}]}<\/script>\r\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Residenza fittizia: cosa si rischia","description":"Cosa si rischia se si dichiara all'anagrafe una residenza fittizia? Seppur porta apparenti vantaggi dichiarare il falso causa reato.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/","og_locale":"it_IT","og_type":"article","og_title":"Residenza fittizia: cosa si rischia","og_description":"Cosa si rischia se si dichiara all'anagrafe una residenza fittizia? Seppur porta apparenti vantaggi dichiarare il falso causa reato.","og_url":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/","og_site_name":"VisureSmart News","article_publisher":"https:\/\/www.facebook.com\/visuresmart.it\/","article_published_time":"2022-03-11T08:00:39+00:00","article_modified_time":"2022-03-01T10:21:28+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg","type":"image\/jpeg"}],"author":"Visuresmart","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Visuresmart","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#article","isPartOf":{"@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/"},"author":{"name":"Visuresmart","@id":"https:\/\/visuresmart.it\/news\/#\/schema\/person\/f2480b0f8a8cfe03fbacc0a5a37f9b28"},"headline":"Residenza fittizia: cosa si rischia","datePublished":"2022-03-11T08:00:39+00:00","dateModified":"2022-03-01T10:21:28+00:00","mainEntityOfPage":{"@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/"},"wordCount":690,"commentCount":0,"publisher":{"@id":"https:\/\/visuresmart.it\/news\/#organization"},"image":{"@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#primaryimage"},"thumbnailUrl":"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg","keywords":["certificato di residenza","residenza","residenza fittizia"],"articleSection":["Casa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/","url":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/","name":"Residenza fittizia: cosa si rischia","isPartOf":{"@id":"https:\/\/visuresmart.it\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#primaryimage"},"image":{"@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#primaryimage"},"thumbnailUrl":"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg","datePublished":"2022-03-11T08:00:39+00:00","dateModified":"2022-03-01T10:21:28+00:00","description":"Cosa si rischia se si dichiara all'anagrafe una residenza fittizia? Seppur porta apparenti vantaggi dichiarare il falso causa reato.","breadcrumb":{"@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#primaryimage","url":"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg","contentUrl":"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2022\/03\/residenza-fittizia-e1646129672711.jpeg","width":1920,"height":1080,"caption":"Cosa si rischia con la residenza fittizia"},{"@type":"BreadcrumbList","@id":"https:\/\/visuresmart.it\/news\/residenza-fittizia-cosa-si-rischia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visuresmart.it\/news\/"},{"@type":"ListItem","position":2,"name":"Residenza fittizia: cosa si rischia"}]},{"@type":"WebSite","@id":"https:\/\/visuresmart.it\/news\/#website","url":"https:\/\/visuresmart.it\/news\/","name":"VisureSmart News","description":"Il blog che nasce con l&#039;intento di aiutarvi a trovare informazioni su casa, famiglia, auto, lavoro e imprese in modo rapido e semplificato!","publisher":{"@id":"https:\/\/visuresmart.it\/news\/#organization"},"alternateName":"Visuresmart","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visuresmart.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/visuresmart.it\/news\/#organization","name":"News VisureSmart.it","url":"https:\/\/visuresmart.it\/news\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/visuresmart.it\/news\/#\/schema\/logo\/image\/","url":"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2020\/03\/Risorsa-2.png","contentUrl":"https:\/\/visuresmart.it\/news\/wp-content\/uploads\/2020\/03\/Risorsa-2.png","width":513,"height":513,"caption":"News VisureSmart.it"},"image":{"@id":"https:\/\/visuresmart.it\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/visuresmart.it\/","https:\/\/www.instagram.com\/visuresmart.it\/"],"description":"Visuresmart.it \u00e8 un portale unico specializzato nella richiesta di documenti burocratici, tanto per i professionisti quanto per i cittadini. I nostri servizi permettono di ottenere un contatto diretto con la Pubblica Amministrazione, l\u2019Anagrafe, la Camera di Commercio e il Tribunale. Il nostro team \u00e8 composto da professionisti del settore, esperti nell\u2019espletare pratiche e capaci di consigliare e indirizzare i nostri clienti verso le soluzioni migliori.","email":"info@visuresmart.it"},{"@type":"Person","@id":"https:\/\/visuresmart.it\/news\/#\/schema\/person\/f2480b0f8a8cfe03fbacc0a5a37f9b28","name":"Visuresmart","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/visuresmart.it\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/27e26115b2431936e33b4fc6115798f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/27e26115b2431936e33b4fc6115798f2?s=96&d=mm&r=g","caption":"Visuresmart"}}]}},"_links":{"self":[{"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/posts\/3466"}],"collection":[{"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/comments?post=3466"}],"version-history":[{"count":0,"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/posts\/3466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/media\/3469"}],"wp:attachment":[{"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/media?parent=3466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/categories?post=3466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visuresmart.it\/news\/wp-json\/wp\/v2\/tags?post=3466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}